{"id":21772,"date":"2022-01-26T17:26:28","date_gmt":"2022-01-26T17:26:28","guid":{"rendered":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/?p=21772"},"modified":"2022-01-26T17:26:31","modified_gmt":"2022-01-26T17:26:31","slug":"las-rosas-la-banda-municipal-manuel-belgrano-de-la-ciudad-cumplio-124-anos","status":"publish","type":"post","link":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/2022\/01\/las-rosas-la-banda-municipal-manuel-belgrano-de-la-ciudad-cumplio-124-anos\/","title":{"rendered":"Las Rosas: La Banda Municipal \u201cManuel Belgrano\u201d de la ciudad cumpli\u00f3 124 a\u00f1os"},"content":{"rendered":"\n<p>La banda es la cuna de encuentro de grandes artistas de la ciudad, donde muchos de ellos dieron sus primeros pasos, para luego seguir con su carrera musical.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.noticiasd.com\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-20-at-12.07.37-PM-1-1024x674.jpeg\" rel=\"lightbox[21772]\"><img decoding=\"async\" src=\"https:\/\/www.noticiasd.com\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-20-at-12.07.37-PM-1-1024x674.jpeg\" alt=\"\" class=\"wp-image-435289\"\/><\/a><\/figure>\n\n\n\n<p>La banda surgi\u00f3 un 19 de enero de 1898 por un grupo de personas que le solicitaron a la&nbsp;<strong>Comisi\u00f3n de Fomento<\/strong>&nbsp;la compra de instrumentos para poder formar el grupo musical.&nbsp; En sus comienzos fue llamada \u201c<strong>Casa ni\u00f1o\u201d<\/strong>, tomando el nombre del lugar donde funcionaba el actual<strong>&nbsp;Centro de Acci\u00f3n Familiar&nbsp;<\/strong>(C.A.F).<\/p>\n\n\n\n<p>Hoy en d\u00eda, gracias a la notable presencia del Municipio de Las Rosas, la banda puede proyectar sus deseos e historia hacia un futuro. De este modo, sus miembros encuentren un lugar no s\u00f3lo donde hacer m\u00fasica de calidad de manera gratuita, sino tambi\u00e9n un lugar donde puedan vincularse, forjar sentido de pertenencia para cuidar a la instituci\u00f3n y as\u00ed lograr que la banda pueda seguir evolucionando con los a\u00f1os.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"740\" src=\"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-20-at-12.07.37-PM-copia-1024x740-1.jpeg\" alt=\"\" class=\"wp-image-21774\" srcset=\"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-20-at-12.07.37-PM-copia-1024x740-1.jpeg 1024w, http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-20-at-12.07.37-PM-copia-1024x740-1-300x217.jpeg 300w, http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-20-at-12.07.37-PM-copia-1024x740-1-768x555.jpeg 768w, http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-20-at-12.07.37-PM-copia-1024x740-1-234x169.jpeg 234w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Fernando Gianolio,&nbsp;<\/strong>director de la banda, comenta que se siente orgulloso de poder hacer m\u00fasica con personas de diversos rangos etarios, y con hermosas personas como&nbsp;<strong>Carlos Ariel Flores Prof. de Trompeta y Tromb\u00f3n, Guillermina Mader\u00f3n Prof. de Clarinete y Co-directora, Gino Porchetti Prof. De Bater\u00eda y Jorge \u201cLaucha\u201d Calcaterra, Prof. de Bajo.<\/strong><\/p>\n\n\n\n<p>Adem\u00e1s, algunos de ellos, este a\u00f1o est\u00e1n cumpliendo 29 a\u00f1os junto al grupo musical, pasando de ser participantes de la misma a integrar la direcci\u00f3n de la banda. Todos conforman un equipo de trabajo con el claro objetivo de que la banda\u00a0<strong>\u201cGr. Manuel Belgrano\u201d\u00a0<\/strong>siga prosperando en el tiempo.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"19-01-22 Nota Fernando Gianolio - Director\" width=\"1016\" height=\"572\" src=\"https:\/\/www.youtube.com\/embed\/f5VhMPEdwqg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La banda es la cuna de encuentro de grandes artistas de la ciudad, donde muchos de ellos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":21773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[8],"tags":[],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-20-at-12.19.45-PM-1024x576-1.jpeg","_links":{"self":[{"href":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/21772"}],"collection":[{"href":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/comments?post=21772"}],"version-history":[{"count":1,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/21772\/revisions"}],"predecessor-version":[{"id":21775,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/21772\/revisions\/21775"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media\/21773"}],"wp:attachment":[{"href":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media?parent=21772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/categories?post=21772"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/tags?post=21772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}