{"id":12039,"date":"2014-01-30T16:56:36","date_gmt":"2014-01-30T16:56:36","guid":{"rendered":"http:\/\/entecultura.com.ar\/usina2\/?p=12039"},"modified":"2014-01-30T16:56:36","modified_gmt":"2014-01-30T16:56:36","slug":"sunchales-olor-a-carnaval","status":"publish","type":"post","link":"http:\/\/enteculturalsantafesino.com.ar\/usina2\/2014\/01\/sunchales-olor-a-carnaval\/","title":{"rendered":"Sunchales: \u00abOlor a Carnaval&#8230;\u00bb"},"content":{"rendered":"<p>Los ensayos ya comenzaron hace algunas semanas. Las batucadas suenan cada tardecita en diferentes sectores de la <a href=\"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-content\/uploads\/2014\/01\/untitled.png\" rel=\"lightbox[12039]\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12040 alignright\" alt=\"untitled\" src=\"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-content\/uploads\/2014\/01\/untitled-300x211.png\" width=\"300\" height=\"211\" srcset=\"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-content\/uploads\/2014\/01\/untitled-300x211.png 300w, http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-content\/uploads\/2014\/01\/untitled.png 620w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>ciudad. Llega el momento de ajustar y darle precisi\u00f3n a los diferentes pasos de baile y coreograf\u00edas. Tambi\u00e9n es hora de realizar los retoques finales a los trajes, espaldares y carrozas. Lentejuelas, piedras y plumas por doquier. La ansiedad de las escuadras por estar frente al p\u00fablico se hace sentir. La motivaci\u00f3n llega a su punto c\u00falmine. Si, se\u00f1oras y se\u00f1ores, lo que ustedes perciben es olor a carnaval.<\/p>\n<p>Poco a poco, se viene definiendo la propuesta de la fiesta popular m\u00e1s importante de toda la regi\u00f3n y que nos identifica como comunidad, la misma que convoca a miles de personas de nuestra ciudad y de localidades vecinas a\u00f1o tras a\u00f1o: los Fabulosos Carnavales Sunchalenses.<\/p>\n<p>En su edici\u00f3n 2014, la Municipalidad de Sunchales apunta a brindar un espect\u00e1culo de primer nivel, avanzando en la jerarquizaci\u00f3n no s\u00f3lo del show sino tambi\u00e9n del cors\u00f3dromo. En esta ocasi\u00f3n, se determin\u00f3 la realizaci\u00f3n de 2 noches de carnaval de alto voltaje, s\u00e1bado 1 y domingo 2 de marzo, con la presencia de 5 comparsas locales (Iruya, Mangueira, Pintados Chiquilines, Maranat\u00e1 y Omaer\u00e1 Ker\u00e1), espect\u00e1culos musicales (ambas noches) y comparsas invitadas. Adem\u00e1s la tradicional elecci\u00f3n de la reina, fuegos artificiales y otras sorpresas.<\/p>\n<p>Al igual que el pasado a\u00f1o, el municipio adhiere al Carnaval Federal de la Alegr\u00eda 2014 organizado por Presidencia de la Naci\u00f3n.<\/p>\n<p>En la segunda quincena de febrero, el gobierno local llevar\u00e1 a cabo una conferencia de prensa con el objetivo de brindar mayores detalles del evento.<br \/>\nConvocatoria de carrozas y taxis locos<\/p>\n<p>Durante el mes de febrero estar\u00e1n abiertas las inscripciones para carrozas y taxis locos que quieran formar parte del espect\u00e1culo de los Fabulosos Carnavales Sunchalenes 2014.<br \/>\nLos interesados deber\u00e1n dirigirse a la Secretar\u00eda del Liceo Municipal (Rotania 702) o comunicarse a la l\u00ednea telef\u00f3nica (03493) 422706 o v\u00eda correo electr\u00f3nico a secretarialiceo@sunchales.gov.ar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ensayos ya comenzaron hace algunas semanas. Las batucadas suenan cada tardecita en diferentes sectores de la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[27],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-content\/uploads\/2014\/01\/untitled.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/posts\/12039"}],"collection":[{"href":"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/comments?post=12039"}],"version-history":[{"count":0,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/posts\/12039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/media\/12040"}],"wp:attachment":[{"href":"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/media?parent=12039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/categories?post=12039"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/tags?post=12039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}