{"id":16191,"date":"2016-03-18T12:16:35","date_gmt":"2016-03-18T12:16:35","guid":{"rendered":"http:\/\/entecultura.com.ar\/usina1\/?p=16191"},"modified":"2016-03-18T12:16:35","modified_gmt":"2016-03-18T12:16:35","slug":"la-comuna-de-aldao-se-suma-al-ente-cultural-santafesino","status":"publish","type":"post","link":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/2016\/03\/la-comuna-de-aldao-se-suma-al-ente-cultural-santafesino\/","title":{"rendered":"La Comuna de Aldao se suma al Ente Cultural Santafesino"},"content":{"rendered":"<p>El <b>Presidente Comunal Ruben Pelosi <\/b>junto a su<b> Secretario de Coordinaci\u00f3n Ricardo Celaya<\/b>\u00a0<strong>,\u00a0<\/strong>mediante nota de\u00a0solicitud\u00a0fundamentan la incorporaci\u00f3n de la comunidad\u00a0de <strong>Aldao<em>,<a href=\"http:\/\/www.facebook.com\/comuna.deramona.5#!\/ComunaDeRamona?fref=ts\">\u00a0<\/a><\/em><\/strong>comprometi\u00e9ndose junto al resto de los integrantes de la<strong> Usina I<\/strong>\u00a0a cumplir con los quehaceres culturales, imbuidos en el precepto de \u201centramado regional, pluralista y democr\u00e1tico\u201d.<\/p>\n<p>Motivo por lo cual el <strong>Ente Cultural Santafesino<\/strong> ha aceptado la solicitud convirti\u00e9ndose en un nuevo adherente, con la finalidad de generar los espacios de promoci\u00f3n y difusi\u00f3n desde la tarea de \u201cregionalizaci\u00f3n\u201d a trav\u00e9s del desarrollo productivo y cultural de nuestras comunidades santafesinas.<\/p>\n<div>Dicho organismo posibilitar\u00e1 la interacci\u00f3n activa de los distintos organismos culturales de cada comunidad participante, logrando acuerdos y pol\u00edticas que reflejen una mayor y mejor jerarquizaci\u00f3n en las gestiones culturales.<\/div>\n<div><\/div>\n<div><b>Aldao<\/b> es una localidad del departamento San Lorenzo, situada a 343 km al noroeste de Buenos Aires, a 139 km de la Ciudad de Santa Fe, a 16 km al noroeste de la cabecera departamental San Lorenzo, y a 39 km de Rosario por ruta pavimentada y por autopista.<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Presidente Comunal Ruben Pelosi junto a su Secretario de Coordinaci\u00f3n Ricardo Celaya\u00a0,\u00a0mediante nota de\u00a0solicitud\u00a0fundamentan la incorporaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":16192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[50],"tags":[],"class_list":["post-16191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aldao"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2016\/03\/12509653_156057921432332_7982226529172516656_n.jpg","_links":{"self":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/16191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/comments?post=16191"}],"version-history":[{"count":0,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/16191\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media\/16192"}],"wp:attachment":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media?parent=16191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/categories?post=16191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/tags?post=16191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}