{"id":17038,"date":"2016-09-21T13:47:17","date_gmt":"2016-09-21T13:47:17","guid":{"rendered":"http:\/\/entecultura.com.ar\/usina1\/?p=17038"},"modified":"2016-09-21T14:06:31","modified_gmt":"2016-09-21T14:06:31","slug":"bustinza-recibio-al-premio-provincial-julio-migno","status":"publish","type":"post","link":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/2016\/09\/bustinza-recibio-al-premio-provincial-julio-migno\/","title":{"rendered":"Bustinza recibi\u00f3 al Premio provincial \u00abJulio Migno\u00bb"},"content":{"rendered":"<p>En sede comunal de la localidad perteneciente al Depto Iriondo, el <strong>Presidente Comunal Fabian Ballori, el Secretario de Cultura Marcelo Brabo, el Secretario de Gobierno Anibal Pagnuco e integrantes de la administraci\u00f3n comunal: Danisa Johansen, Silvia Vega \u00a0y Luciana Gutierrez<\/strong> recibieron en la jornada del <strong>mi\u00e9rcoles 21<\/strong> al <strong>Premio Provincial \u00abJulio Migno\u00bb.<\/strong><\/p>\n<p>Desde el <a href=\"http:\/\/www.enteculturalsantafesino.com.ar\/\">Ente Cultural Santafesino <\/a>se origin\u00f3 y organiz\u00f3 un recorrido provincial a trav\u00e9s de los Centros Tradicionalistas, Comunas, Municipios, entidades educativas y culturales de m\u00e1s de noventa localidades posibilitando llegar a cada rinc\u00f3n santafesino con el premio que ser\u00e1 entregado por segundo a\u00f1o consecutivo durante la \u201cFiesta de los Pueblos\u201d el 5 de diciembre en la ciudad de Santa Fe.<\/p>\n<p>La estatuilla con la imagen del sacerdote Florian Paucke, abrazando un ni\u00f1o ind\u00edgena, la cual parti\u00f3 desde San Javier luego de un encuentro en la Iglesia de esa ciudad, siendo trasladado hasta Helvecia por una comitiva, continua con su recorrido por m\u00e1s de 90 localidades de la provincia de Santa Fe, posibilitando que cada rinc\u00f3n santafesino proponga aspirantes a esta recompensa: un premio que anhela tener el prestigio necesario para ser un digno reconocimiento a quien lo reci<span class=\"text_exposed_show\">ba.<\/span><\/p>\n<p>El creador del premio, Alejandro Vivas, manifest\u00f3 que \u201cdesde San Javier conocen que era el sue\u00f1o del poeta Julio Migno que se tuviera un premio a nivel provincial, es por esto que se promueve esta imagen, representada por Florian Paucke, evangelizador jesuita, con una mano sobre el hombro de un ni\u00f1o aborigen, ya que se considera que con este encuentro se origina la verdadera uni\u00f3n de culturas\u201d.<\/p>\n<div class=\"text_exposed_show\">\n<p>\u201cEn vida no obtuvo el homenaje que se merecen las personas de su estirpe intelectual y moral y este es el momento de la reivindicaci\u00f3n\u201d, se\u00f1al\u00f3. \u201cNo se debe desconocer que sus obras han sido premiadas en el \u00e1mbito nacional e internacional y comparadas en el alg\u00fan momento a la obra de Jos\u00e9 Hern\u00e1ndez, denomin\u00e1ndolo el \u201cMart\u00edn Fierro de la Costa\u201d, finaliz\u00f3 Alejandro Vivas.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En sede comunal de la localidad perteneciente al Depto Iriondo, el Presidente Comunal Fabian Ballori, el Secretario [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":17039,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[44,38],"tags":[],"class_list":["post-17038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bustinza","category-gestiones-e-c"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2016\/09\/14423637_291013441284802_1659297477_o.jpg","_links":{"self":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/17038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/comments?post=17038"}],"version-history":[{"count":0,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/17038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media\/17039"}],"wp:attachment":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media?parent=17038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/categories?post=17038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/tags?post=17038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}