{"id":17051,"date":"2016-09-25T16:33:41","date_gmt":"2016-09-25T16:33:41","guid":{"rendered":"http:\/\/entecultura.com.ar\/usina1\/?p=17051"},"modified":"2016-09-25T16:33:41","modified_gmt":"2016-09-25T16:33:41","slug":"una-noche-de-encuentros-y-produccion-cultural-se-vivio-en-pena-el-amanecer","status":"publish","type":"post","link":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/2016\/09\/una-noche-de-encuentros-y-produccion-cultural-se-vivio-en-pena-el-amanecer\/","title":{"rendered":"Una noche de encuentros y producci\u00f3n cultural se vivi\u00f3 en Pe\u00f1a \u00abEl Amanecer\u00bb"},"content":{"rendered":"<p>El pasado viernes\u00a0<strong>viernes 23 de septiembre <\/strong>en la localidad de<strong> Correa (Depto. Iriondo)<\/strong>\u00a0la distinguida e historica\u00a0<strong>Pe\u00f1a \u201cEl Amanecer\u201d <\/strong>present\u00f3 para los distintos secretarios, directores y referentes culturales de la Usinas I y III\u00a0dos obras art\u00edsticas:\u00a0<strong><em>\u201cAqu\u00ed me pongo a bailar\u201d<\/em> <\/strong>y <em><strong>\u201cLa Patriada\u201d<\/strong><\/em><\/p>\n<p>La noche cont\u00f3 con la presencia del P<em>residente del Ente Cultural Santafesino. Leonardo Carrozza, de la Diputada Provincial Claudia Giaccone, el Presidente Comunal de Lucio V L\u00f3pez Pablo Sullivan,el Coordinador del ECS Prof. Fernando Banegas, los directores de las Usina I, III y V Marcela Geminale, Sandra Maidana y Ernesto Paul\u00f3n junto los representantes culturales de las comunidades de: Villa Elo\u00edsa, Salto Grande, Lucio V. L\u00f3pez, Zavalla, Maria Susana, Wheelwright, Chovet, Capit\u00e1n Bermudez, Labordeboy, Los Quirquinchos y Montes de Oca.<\/em><\/p>\n<p><strong>Leonardo Carrozza Presidente del Ente Cultural<\/strong> agradeci\u00f3 la predisposici\u00f3n y atenci\u00f3n de la Pe\u00f1a quienes ademas brindaron un espect\u00e1culo que permitir\u00e1 difundir y promover en distintas etapas a trav\u00e9s del programa <strong>\u00abCompartiendo Cultura\u00bb<\/strong> y posibilitar la llegada de esta propuesta a los pueblos y \u00a0ciudades del Ente Cultural.<\/p>\n<p>La <strong>Diputada Giaccone<\/strong> se\u00f1al\u00f3 el trabajo que se viene desarrollando en Correa junto a la <strong>Biblioteca Popular<\/strong> y la <strong>Pe\u00f1a<\/strong>. <em>\u00abGeneramos una agenda muy importante , fortaleciendo el quehacer cultural de toda una regi\u00f3n y provincia. Es por esto, que Pe\u00f1a \u00abEl\u00a0Amanecer\u00a0el pr\u00f3ximo 30 de noviembre recibir\u00e1 un reconocimiento a la trayectoria, pudiendo adem\u00e1s,\u00a0disfrutar de su arte en el hall de la Legislatura provincial.<\/em><\/p>\n<p><strong>\u201cAqu\u00ed me pongo a bailar\u201d<\/strong>\u00a0<em>Trabajo realizado por todos los ni\u00f1os de esta instituci\u00f3n que en forma gratuita asisten a su casa y que funciona como tal desde hace 41 a\u00f1os. La obra esta pensada para chicos y efectuada por los chicos. Por tal motivo y teniendo en cuenta el desconocimiento de ellos sobre la historia de Jos\u00e9 Hern\u00e1ndez, buscamos la manera de unir en lenguaje simple y claro las diferentes danzas. Se cuentan las peripecias m\u00e1s destacadas y atractivas de manera entendible para su edad y a la vez, que les resulte interesante descubrirla desde la lectura. El campo, la pulperia, la pelea, la payada, la fuga y el regreso son partes de \u00e9sta historia bailada por ni\u00f1os de 6 a 13 a\u00f1os.<\/em><\/p>\n<p><strong>\u201cLa Patriada\u201d:\u00a0<\/strong><em>El Ballet mayor presentar\u00e1 un cuadro donde al apreciar los relatos y las frases del mismo dar\u00e1n los motivos suficientes para saber definir lo que se est\u00e1 transmitiendo desde el escenario. Aires de triunfo y malambo hacen que el celeste y blanco prime en \u201cLa patriada\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado viernes\u00a0viernes 23 de septiembre en la localidad de Correa (Depto. Iriondo)\u00a0la distinguida e historica\u00a0Pe\u00f1a \u201cEl [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":17053,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[21,38],"tags":[],"class_list":["post-17051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-correa","category-gestiones-e-c"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2016\/09\/IMG_4267.jpg","_links":{"self":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/17051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/comments?post=17051"}],"version-history":[{"count":0,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/17051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media\/17053"}],"wp:attachment":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media?parent=17051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/categories?post=17051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/tags?post=17051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}