{"id":17442,"date":"2017-02-28T19:18:06","date_gmt":"2017-02-28T19:18:06","guid":{"rendered":"http:\/\/entecultura.com.ar\/usina1\/?p=17442"},"modified":"2017-02-28T19:18:06","modified_gmt":"2017-02-28T19:18:06","slug":"de-palo-a-pique-de-julio-migno-inicia-su-recorrido-por-todo-el-suelo-santafesino","status":"publish","type":"post","link":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/2017\/02\/de-palo-a-pique-de-julio-migno-inicia-su-recorrido-por-todo-el-suelo-santafesino\/","title":{"rendered":"\u00abDe Palo a Pique\u00bb de Julio Migno, inicia su recorrido por todo el suelo santafesino"},"content":{"rendered":"<p>El pr\u00f3ximo <strong>viernes 3<\/strong> en las comunidades de <strong>Coronel Arnold<\/strong> e <strong>Ibarlucea<\/strong> se presentar\u00e1 la re-edici\u00f3n del libro <strong>\u00abDe Palo a Pique\u00bb<\/strong> del destacado\u00a0escritor costero, Julio Migno.<\/p>\n<p><strong>Dichas presentaciones dar\u00e1n inicio a la gira 2017 por las comunidades adheridas al Ente Cultural Santafesino junto a la Sra Olga Migno (hija del escritor) quien llevar\u00e1 su obra a cada rinc\u00f3n santafesino.<\/strong><\/p>\n<p>Es importante destacar que esta re-edici\u00f3n fue llevada a cabo por la <strong>Fundaci\u00f3n Julio Migno<\/strong> y la <strong>Diputada Provincial Claudia Giaccone<\/strong>,\u00a0permitiendo la publicaci\u00f3n de 500 ejemplares, los cuales ser\u00e1n expuestos en\u00a0cada localidad visitada,\u00a0durante el corriente a\u00f1o.<\/p>\n<p><em>\u201cA<\/em><span class=\"text_exposed_show\"><em> trav\u00e9s de la Imprenta Legislativa de la C\u00e1mara de Santa Fe, es un orgullo poder ser parte de esta iniciativa junto a sus hijas y a la Fundaci\u00f3n Julio Migno, que es el comienzo de futuras re-ediciones\u00a0de su profusa obra y que a trav\u00e9s del Ente Cultural Santafesino vuelve a aparecer en el territorio para ser disfrutado<\/em>\u201c, se\u00f1al\u00f3 la Diputada Giaccone.<\/span><\/p>\n<p><strong>Coronel Arnold:<\/strong><\/p>\n<p>En el marco del\u00a0<strong>11\u00b0 Encuentro Nacional de Difusores<\/strong> a partir de las <strong>16hs<\/strong> se presentar\u00e1 el libro<strong> \u00abDe Palo a Pique\u00bb<\/strong> en la <strong>Plaza San Mart\u00edn.<\/strong><\/p>\n<p><strong>Ibarlucea:<\/strong><\/p>\n<p>A partir de las <strong>19:30hs<\/strong> en el <strong>Sal\u00f3n Comunal \u00abUni\u00f3n y Progreso\u00bb<\/strong> <em>(San Mart\u00edn y Maip\u00fa)<\/em> la <strong>Biblioteca Popular y Centro Cultural Julio Migno<\/strong> presentar\u00e1n dicha re-edici\u00f3n del magistral poeta sanjavierino.<\/p>\n<p><strong>Biograf\u00eda<\/strong><\/p>\n<p><strong>Julio Migno Parera:<\/strong>\u00a0Naci\u00f3 en\u00a0San Javier,\u00a0provincia de Santa Fe, el\u00a06 de octubre\u00a0de\u00a01915\u00a0y muri\u00f3 el\u00a05 de diciembre\u00a0de\u00a01993\u00a0en la ciudad de\u00a0Santa Fe\u00a0Fue una persona de un lenguaje sencillo y sensible que lo llev\u00f3 a destacarse como poeta, su poes\u00edas abarcaba la naturaleza salvaje de su tierra, las soledades y silencios de los pobladores isleros, el mensaje humano.<\/p>\n<p>En 1932 aparece \u201cA los nuestros\u201d, peque\u00f1o volumen de poes\u00edas en colaboraci\u00f3n con F\u00e9lix Villasur. En 1943 cristaliza su primera obra de aliento, Amargas, donde la confluencia de indio, espa\u00f1ol y gringo es la trama por donde palpita el criollo, esencia del ser nuevo.<\/p>\n<p>En 1947 publica Yerbag\u00fcena, su obra cumbre, a la que la B.B.C. de Londres compara con la obra m\u00edstica de Bunyan.\u00a0En 1952 aparece Chira Molina, testimonio desgarrado de un personaje valiente y desafortunado, marcado por la injusticia social imperante.\u00a0En esta obra se destacan temas como \u201cSi ten\u00e9s cachorro\u201d, \u201cMis islas son eso\u201d y \u201cEl bolicho\u201d, entre otros.\u00a0En 1955 la Colecci\u00f3n del Litoral edita una recopilaci\u00f3n antol\u00f3gica: Cardos y estrellas.<\/p>\n<p>En 1965 ve la luz otra antolog\u00eda, De palo a pique, que al igual que el resto de las obras, alcanzar\u00eda varias ediciones. Miquichises, de 1972, incluye temas de vasta repercusi\u00f3n popular, tales como \u201cVersos pa negro y guitarra\u201d, \u201cRomance del indio gringo\u201d, \u201cEl hondazo\u201d, \u201cLa flauta de Paiki, \u201cVersos al indio que llevo\u201d y \u201cSan Francisco Javier\u201d.<\/p>\n<p>De neto corte castellano y con toda la carga l\u00edrica del tiempo y su marcha, da a la prensa, en 1987, Summa Poetica.\u00a0A lo largo de su trayectoria literaria, el autor ha recibido innumerables premios y distinciones. Llevan su nombre numerosas instituciones entre las que figuran escuelas y bibliotecas p\u00fablicas, as\u00ed como agrupaciones de orden diverso.<\/p>\n<p>El escritor dej\u00f3 su cuerpo f\u00edsico el 5 de diciembre de 1993 en la ciudad de Santa Fe. Sus restos descansan en el cementerio municipal de San Javier. Su obra sigue vigente a trav\u00e9s de su inclusi\u00f3n tanto en distintos planes de estudio como en diversas y fervorosas demostraciones de la cultura popular.<\/p>\n<p>La <strong>Fundaci\u00f3n Julio Migno<\/strong>, est\u00e1 abocada tanto a la difusi\u00f3n de su obra como a la participaci\u00f3n del rescate de los valores aut\u00f3ctonos. Dentro de su ideario figura la fidelidad al mensaje de la obra del autor en lo referente a los grupos o sectores menos protegidos de la sociedad as\u00ed como a aquellos cuya patente vulnerabilidad los transforma en sujetos de esmerado cuidado y dedicaci\u00f3n sociocultural.<\/p>\n<h1 class=\"item-page-title\"><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo viernes 3 en las comunidades de Coronel Arnold e Ibarlucea se presentar\u00e1 la re-edici\u00f3n del [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":17443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[56,38,55],"tags":[],"class_list":["post-17442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronel-arnold","category-gestiones-e-c","category-ibarlucea"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2017\/02\/IMG_2295.jpg","_links":{"self":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/17442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/comments?post=17442"}],"version-history":[{"count":0,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/17442\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media\/17443"}],"wp:attachment":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media?parent=17442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/categories?post=17442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/tags?post=17442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}