{"id":17988,"date":"2017-08-29T14:36:36","date_gmt":"2017-08-29T14:36:36","guid":{"rendered":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/?p=17988"},"modified":"2017-08-29T14:36:36","modified_gmt":"2017-08-29T14:36:36","slug":"el-trebol-se-presenta-fiesta-de-arte-en-la-ciudad","status":"publish","type":"post","link":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/2017\/08\/el-trebol-se-presenta-fiesta-de-arte-en-la-ciudad\/","title":{"rendered":"El Tr\u00e9bol: Se presenta Fiesta de Arte en la Ciudad"},"content":{"rendered":"<p>El martes por la ma\u00f1ana, desde las 10hs, las autoridades locales y coordinadores de Fiesta de Arte en la ciudad, presentar\u00e1n oficialmente el evento que se llevar\u00e1 a cabo entre el 6 y el 12 de septiembre.<\/p>\n<p>En la misma, estar\u00e1n presentes el Intendente Fernando Almada, el director de Desarrollo Cultural Jorge Meynet, miembros del gabinete municipal, Graciela Pons como coordinadora general, los responsables de la 1\u00aa Fiesta del Arte de Asar a la estaca y de la Expo Multimarca, colaboradores y p\u00fablico en general.<\/p>\n<p>A trav\u00e9s de la conferencia de presa se conocer\u00e1n los espect\u00e1culos, talleres y trabajos que se realizar\u00e1n en cada uno de los siete d\u00edas que durar\u00e1 esta propuesta cultural y art\u00edstica que ya forma parte de la ciudad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El martes por la ma\u00f1ana, desde las 10hs, las autoridades locales y coordinadores de Fiesta de Arte [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":17989,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[18],"tags":[],"class_list":["post-17988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-trebol"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2017\/08\/dsc_2040.jpg","_links":{"self":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/17988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/comments?post=17988"}],"version-history":[{"count":0,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/17988\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media\/17989"}],"wp:attachment":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media?parent=17988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/categories?post=17988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/tags?post=17988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}