{"id":18340,"date":"2018-01-25T12:50:03","date_gmt":"2018-01-25T12:50:03","guid":{"rendered":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/?p=18340"},"modified":"2018-01-25T12:50:03","modified_gmt":"2018-01-25T12:50:03","slug":"el-trebol-la-troupe-de-los-autos-locos-uno-de-los-atractivos-del-carnaval-2018","status":"publish","type":"post","link":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/2018\/01\/el-trebol-la-troupe-de-los-autos-locos-uno-de-los-atractivos-del-carnaval-2018\/","title":{"rendered":"El  Tr\u00e9bol: \u201cLa Troupe de los Autos Locos\u201d, uno de los atractivos del Carnaval 2018"},"content":{"rendered":"<p>La noche del 11 de febrero promete ser inolvidable con un sinf\u00edn de propuestas para disfrutar de principio a fin.<\/p>\n<p>Adem\u00e1s de comparsas, carrozas, disfrazados, baile y variados show musicales, se desplegar\u00e1 por el cors\u00f3dromo de Av. Libertad un espect\u00e1culo \u00fanico.<\/p>\n<p>Se trata de autos que llegan desde Lincoln (Bs. As) de la mano de la familia Bernini, que desfilan por el cors\u00f3dromo con normalidad y de repente, a trav\u00e9s de una maniobra, hacen cosas disparatadas que llaman la atenci\u00f3n de la gente: se desarman en dos y tres partes cada una con chofer y movilidad propia, bailan sobre las ruedas traseras, hacen movimientos de fuelle, \u201cWilly\u201d invertido, se abalanzan, dan vueltas carnero, saltan como ranas, vuelcan y vuelven al estado normal, hacen trompos, se despliegan como un \u201cTransformer\u201d y todo lo que se imaginen.<\/p>\n<p>Son populares en todo el pa\u00eds, recorren los distintos espect\u00e1culos y carnavales de la regi\u00f3n, llevando alegr\u00eda y diversi\u00f3n. Hace poco, estuvieron haciendo su presentaci\u00f3n \u00a0en el programa \u201cLo mejor de la familia\u201d de Canal 13 conducido por Guido Kaczka.<\/p>\n<p>\u201cLa Troupe de los Autos locos\u201d, llega a El Tr\u00e9bol con una flota de disparatados veh\u00edculos para alegrar la noche de Carnaval.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La noche del 11 de febrero promete ser inolvidable con un sinf\u00edn de propuestas para disfrutar de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18341,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[18],"tags":[],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2018\/01\/17190516_1447689448583383_2609179479819319572_n.jpg","_links":{"self":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/18340"}],"collection":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/comments?post=18340"}],"version-history":[{"count":0,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/18340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media\/18341"}],"wp:attachment":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media?parent=18340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/categories?post=18340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/tags?post=18340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}