{"id":19819,"date":"2018-12-17T13:52:12","date_gmt":"2018-12-17T13:52:12","guid":{"rendered":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/?p=19819"},"modified":"2018-12-17T13:52:19","modified_gmt":"2018-12-17T13:52:19","slug":"las-parejas-masiva-concurrencia-en-el-mercado-navideno","status":"publish","type":"post","link":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/2018\/12\/las-parejas-masiva-concurrencia-en-el-mercado-navideno\/","title":{"rendered":"Las Parejas:  Masiva concurrencia en el Mercado Navide\u00f1o"},"content":{"rendered":"\n<p>Este domingo en el predio del ferrocarril y con una masiva concurrencia, se llev\u00f3 a cabo la segunda edici\u00f3n del Mercado Navide\u00f1o, con la presencia de los distintos comercios de nuestra ciudad en todos los rubros, sumados al patio de comidas, paseo de artesanos, rinc\u00f3n de las artes, inflables, shows en vivo y la presencia de Pap\u00e1 Noel para los m\u00e1s chicos.<\/p>\n\n\n\n<p>Las actividades comenzaron desde las 18hs. con los espect\u00e1culos infantiles en el escenario, para posteriormente disfrutar de la actuaci\u00f3n de la Banda Municipal y los shows tributo a Luciano Pereyra, la actuaci\u00f3n de Troncales y el cierre del Aclamado Amistad.<\/p>\n\n\n\n<p>El Intendente Horacio Compagnucci se dirigi\u00f3 a los presentes agradeciendo \u201ca todos los expositores, artesanos, los stands de comercios y el patio de comidas por confiar en el objetivo principal que es repuntar la actividad comercial y fortalecer la fuente de trabajo de ese sector\u201d, expres\u00f3; \u201cquer\u00edamos que la gente pueda hacer sus compras previas a la Navidad y montar espect\u00e1culos para disfrutar en familia\u201d, dijo; \u201cquiero desearles en un a\u00f1o largo y duro de trabajo para todos una feliz Navidad y que la pasemos en paz y familia, que el 2019 comience mejor de lo que fue este 2018 y lo podamos festejar, hagamos un esfuerzo entre todos y pedirles que lo hagamos libre de pirotecnia, tenemos que acostumbrarnos a festejar &nbsp;tratando de colaborar con cuidar al otro, sabemos los problemas que trae, por eso les pido que evitemos el uso de pirotecnia y tengamos unas fiestas en paz\u201d, solicit\u00f3 Compagnucci, para pedir en el final que el 2019 \u201cvenga mucho mejor &nbsp;de lo que termina este 2018\u201d.<\/p>\n\n\n\n<p>Luego, en conceptos a Radio Las Parejas, Compagnucci admiti\u00f3 estar muy contento \u201cpor este segundo Mercado Navide\u00f1o que tuvo sus frutos, busc\u00e1bamos darle una herramienta a los comercios en estos momentos flojos y funcion\u00f3 muy bien\u201d, coment\u00f3; \u201caparentemente todos los comercios han trabajado muy bien y se ha cerrado positivamente este segundo mercado\u201d, agreg\u00f3, remarcando que son fechas claves que al comercio local le sirve, \u201ces la posibilidad de hacer una compra a precios m\u00e1s bajos en costos y con variedad de productos\u201d, finaliz\u00f3.<\/p>\n\n\n\n<p><strong><em>Fuente: Radio Las Parejas<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este domingo en el predio del ferrocarril y con una masiva concurrencia, se llev\u00f3 a cabo la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19820,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[10],"tags":[],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2018\/12\/48375894_2227308100824208_2305400369884168192_n.jpg","_links":{"self":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/19819"}],"collection":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/comments?post=19819"}],"version-history":[{"count":0,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/19819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media\/19820"}],"wp:attachment":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media?parent=19819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/categories?post=19819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/tags?post=19819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}