{"id":19954,"date":"2019-02-13T14:35:43","date_gmt":"2019-02-13T14:35:43","guid":{"rendered":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/?p=19954"},"modified":"2019-02-13T14:35:49","modified_gmt":"2019-02-13T14:35:49","slug":"el-trebol-todavia-tenes-tiempo-de-ser-parte-de-la-escuela-de-musica","status":"publish","type":"post","link":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/2019\/02\/el-trebol-todavia-tenes-tiempo-de-ser-parte-de-la-escuela-de-musica\/","title":{"rendered":"El Tr\u00e9bol: Todav\u00eda ten\u00e9s tiempo de ser parte de la Escuela de M\u00fasica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un nuevo ciclo lectivo de la Escuela de M\u00fasica Municipal est\u00e1 por iniciarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el inicio del mes de marzo, los alumnos comenzar\u00e1n a transitar nuevas experiencias y a tomar nuevos saberes musicales en una amplia variedad de instrumentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas las personas que deseen ser parte de este proyecto pueden inscribirse en el Centro Cultural Cervantes de lunes a viernes de 8.30 a 12hs y de 17 a 21hs. o llamando al tel\u00e9fono 420011.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El aprendizaje es amplio y variado, con instrumentos de cuerda, viendo y percusi\u00f3n, entre ellos &nbsp;piano, guitarra, xilof\u00f3n, charango, percusi\u00f3n, viol\u00edn, saxo, flauta, bajo, contrabajo, bater\u00eda y otros que se pueden consultar. Tambi\u00e9n el canto formar\u00e1 parte de la grilla de propuestas de la escuela musical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como novedad, y para ampliar las oportunidades, en este 2019 las clases ser\u00e1n por la ma\u00f1ana y la tarde. De este modo, habr\u00e1 m\u00e1s horarios y disponibilidad para que la comunidad pueda acercarse y aprender.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuevo ciclo lectivo de la Escuela de M\u00fasica Municipal est\u00e1 por iniciarse. En el inicio del [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[18],"tags":[],"class_list":["post-19954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-trebol"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2019\/02\/DSC_0067-1.jpg","_links":{"self":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/19954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/comments?post=19954"}],"version-history":[{"count":0,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/19954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media\/19955"}],"wp:attachment":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media?parent=19954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/categories?post=19954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/tags?post=19954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}