{"id":20065,"date":"2019-07-04T14:14:47","date_gmt":"2019-07-04T14:14:47","guid":{"rendered":"http:\/\/enteculturalsantafesino.com.ar\/usina1\/?p=20065"},"modified":"2019-07-04T14:14:53","modified_gmt":"2019-07-04T14:14:53","slug":"llega-el-concurso-de-cortometrajes-hacelo-corto-2019","status":"publish","type":"post","link":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/2019\/07\/llega-el-concurso-de-cortometrajes-hacelo-corto-2019\/","title":{"rendered":"Llega el Concurso de Cortometrajes \u00abHacelo Corto 2019\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El\u00a0<strong>Ente Cultural Santafesino<\/strong>\u00a0convoca al\u00a0<strong>Sexto Concurso de Cortometrajes \u201cHacelo Corto\u201d<\/strong>,\u00a0organizado por el\u00a0<strong>Ente Cultural Santafesino<\/strong> y auspiciado por la <strong>Diputada Provincial Claudia Giaccone<\/strong>; para el cual se fijan las siguientes bases y condiciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podr\u00e1n participar de dicho concurso: <em>instituciones educativas (formales o no formales) y\u00a0productores independientes de localidades adheridas al Ente cultural Santafesino.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las&nbsp;instituciones educativas participantes podr\u00e1n ser de car\u00e1cter p\u00fablico o privado y de cualquier&nbsp;nivel (inicial, primaria, media, adultos, art\u00edstica y especial). Quedando excluida la participaci\u00f3n<br>de cualquier persona que tenga relaci\u00f3n directa con el Ente Cultural Santafesino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CATEGOR\u00cdAS<\/strong><br>Quedan establecidas las siguientes categor\u00edas de participaci\u00f3n:<br>A- instituciones de Nivel Primario<br>B- Instituciones de Nivel medio<br>C- Instituciones de Educaci\u00f3n Especial (pueden optar por inscribirse en esta categor\u00eda o<br>en la categor\u00eda que corresponda a las edades de los alumnos participantes)<br>D- Productores Independientes<br>Cada instituci\u00f3n podr\u00e1 presentar hasta 4 (cuatro) cortometrajes. Y en el caso de los<br>productores independientes, se admitir\u00e1n hasta 2 (dos) cortometrajes<br><strong>PRE INSCRIPCI\u00d3N<\/strong><br>Se establece una PRE-INSCRIPCI\u00d6N de car\u00e1cter obligatorio, por medio de mail especificando<br>los siguientes datos:<br>\u2013 Nombre y Apellido del realizador (o de la instituci\u00f3n, detallando Grado, turno y<br>docente)<br>\u2013 Domicilio, tel\u00e9fono y mail de referencia<br>\u2013 T\u00edtulo tentativo de la obra a presentar y duraci\u00f3n estimada de la misma<br>La fecha l\u00edmite de PRE-INSCRIPCI\u00d3N se establece el d\u00eda <strong>27 de Septiembre de 2019<\/strong> no siendo\u00a0necesario enviar el corto en esta instancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para mayor informaci\u00f3n, consultar las bases<\/strong><br><strong>en: http:\/\/enteculturalsantafesino.com.ar\/hacelocorto\/<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0Ente Cultural Santafesino\u00a0convoca al\u00a0Sexto Concurso de Cortometrajes \u201cHacelo Corto\u201d,\u00a0organizado por el\u00a0Ente Cultural Santafesino y auspiciado por la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":20066,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[38],"tags":[],"class_list":["post-20065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestiones-e-c"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-content\/uploads\/2019\/07\/66113864_357675931615604_4747520771549560832_n.jpg","_links":{"self":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/20065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/comments?post=20065"}],"version-history":[{"count":0,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/posts\/20065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media\/20066"}],"wp:attachment":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/media?parent=20065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/categories?post=20065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina1\/wp-json\/wp\/v2\/tags?post=20065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}