{"id":2244,"date":"2012-02-29T01:10:51","date_gmt":"2012-02-29T01:10:51","guid":{"rendered":"http:\/\/entecultura.com.ar\/noticias\/?p=2244"},"modified":"2012-02-29T01:10:51","modified_gmt":"2012-02-29T01:10:51","slug":"carnavales-en-maria-juana","status":"publish","type":"post","link":"https:\/\/enteculturalsantafesino.com.ar\/usina2\/2012\/02\/carnavales-en-maria-juana\/","title":{"rendered":"CARNAVALES EN MAR\u00cdA JUANA"},"content":{"rendered":"<p><a href=\"http:\/\/enteregionalcultura.com.ar\/usina1\/wp-content\/uploads\/2012\/02\/autor_clubes.jpg\" rel=\"lightbox[2244]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-2245\" title=\"autor_clubes\" src=\"http:\/\/enteregionalcultura.com.ar\/usina1\/wp-content\/uploads\/2012\/02\/autor_clubes-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<table width=\"779\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"341\">\n<div align=\"justify\">Una noche espectacular vivi\u00f3 la comunidad de Mar\u00eda<br \/>\nJuana en la noche de carnaval del domingo. El paseo Antonio Boero fue el lugar<br \/>\nelegido para albergar a las ciento de personas que se acercaron, no solo de<br \/>\nnuestro pueblo sino de localidades vecinas.<br \/>\nTodo comenz\u00f3 con las palabras de<br \/>\nbienvenida de quienes estuvieron en la organizaci\u00f3n. Por un lado el presidente<br \/>\nde Talleres, Germ\u00e1n Barcelo y Julio Acosta por parte de Atl\u00e9tico en reemplazo<br \/>\ndel presidente de esa instituci\u00f3n, ambos coincidieron en agradecer a los<br \/>\npresentes\u00a0 por estar y en lo fruct\u00edfero de trabajar juntos por su<br \/>\ngente.<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" height=\"385\">\n<p align=\"justify\">Luego se dirigi\u00f3 a los presentes el presidente comunal<br \/>\nDr. Eduardo Abdo\u00a0 quien pondero la idea del trabajo en conjunto de ambas<br \/>\ninstituciones.<br \/>\nLa MURGA FUSION\u00a0 \u00abUn espacio para todos\u00bb,\u00a0 que depende del<br \/>\n\u00c1rea de Cultura y Educaci\u00f3n de la Comuna Local deleito a los presentes por sus<br \/>\ntrajes aunque lo m\u00e1s destacado es la integraci\u00f3n de diversos grupos.<br \/>\nPara<br \/>\ncontinuar fueron las reinas de ambos clubes quienes ataviadas con sus atributos<br \/>\ndesfilaron en el \u00abcors\u00f3dromo\u00bb. Joaquina Lovera (CAMJ) y Sof\u00eda Bonino<br \/>\n(CAT).<br \/>\nDesfilaron deportistas de ambas instituciones con banderas y<br \/>\npancartas.<br \/>\nLas alumnas de pat\u00edn del CAT\u00a0 presentaron su comparsa \u00abNegra Ver\u00e1\u00bb<br \/>\njunto a la mascota, un pat\u00edn gigante.<br \/>\nMam\u00e1s, abuelas, mascaritas aportaron al<br \/>\nespect\u00e1culo con la diversi\u00f3n y el humor.<br \/>\nOtro de los momentos fue la<br \/>\npresentaci\u00f3n de la comparsa \u00abMburucuya Vera\u00bb de Estaci\u00f3n Clusellas con 120<br \/>\nintegrantes, con un despliegue de ritmo, color y trajes. La tem\u00e1tica presentada,<br \/>\nel espacio. La comparsa tiene una banda en vivo que los acompa\u00f1a con la batucada<br \/>\ny las canciones propias del carnaval.<br \/>\nEn la continuidad de esta fiesta el<br \/>\nGrupo Domino no solo le puso ritmo y m\u00fasica a la noche, sino que el humor hizo<br \/>\nre\u00edr a los presentes.<br \/>\nPasadas las 3 de la madrugada\u00a0 el p\u00fablico disfrutaba<br \/>\ndel baile y el buffet.<br \/>\nEs para destacar la uni\u00f3n en el grupo de trabajo<br \/>\narmado entre Atl\u00e9tico y Talleres, quienes desde la ma\u00f1ana muy<br \/>\ntemprano comenzaron con los preparativos y cerca de las 5 de la ma\u00f1ana daban por<br \/>\nfinalizado el carnaval en el pueblo, con la satisfacci\u00f3n de haber hecho todo por<br \/>\nsus respectivas instituciones.<br \/>\nDespu\u00e9s de varias d\u00e9cadas\u00a0 el carnaval volvi\u00f3<br \/>\na Mar\u00eda Juana&#8230;y para quedarse&#8230;!<br \/>\nDespu\u00e9s de esta noche, m\u00e1s que nunca se<br \/>\npuede decir&#8230;LA UNION HACE LA FUERZA&#8230;.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" valign=\"top\" height=\"977\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Una noche espectacular vivi\u00f3 la comunidad de Mar\u00eda Juana en la noche de carnaval del domingo. El [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[11,15],"tags":[],"class_list":["post-2244","post","type-post","status-publish","format-standard","hentry","category-eventos","category-maria-juana"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/posts\/2244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/comments?post=2244"}],"version-history":[{"count":0,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/posts\/2244\/revisions"}],"wp:attachment":[{"href":"https:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/media?parent=2244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/categories?post=2244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enteculturalsantafesino.com.ar\/usina2\/wp-json\/wp\/v2\/tags?post=2244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}